{"id":6524,"date":"2019-07-26T11:34:14","date_gmt":"2019-07-26T11:34:14","guid":{"rendered":"http:\/\/blog.educainternet.es\/?p=6524"},"modified":"2020-01-10T13:13:15","modified_gmt":"2020-01-10T13:13:15","slug":"busqueda-de-recursos-libres","status":"publish","type":"post","link":"https:\/\/blog.educainternet.es\/index.php\/2019\/07\/26\/busqueda-de-recursos-libres\/","title":{"rendered":"B\u00fasqueda de recursos libres"},"content":{"rendered":"\n<h2>B\u00fasqueda de recursos libres<\/h2>\n\n\n\n<p>\u00bfHab\u00e9is pensado alguna vez si se puede utilizar todo lo que encontramos online?<\/p>\n\n\n\n<p>La respuesta es sencilla. <strong>No se puede.<\/strong><\/p>\n\n\n\n<p>Pero entonces, \u00bftengo que crearme todos los materiales con herramientas de autor y aprender a utilizar m\u00faltiples de ellas o comprar contenidos pagando con el bajo presupuesto con el que cuenta un profesor? <\/p>\n\n\n\n<p>La respuesta tambi\u00e9n es sencilla. <strong>No hace falta.<\/strong><\/p>\n\n\n\n<p>En esta ocasi\u00f3n desde EducaInternet os contamos c\u00f3mo realizar b\u00fasqueda de contenidos libres que podamos utilizar en nuestra labor docente. La clave estar\u00e1 en las licencias de contenidos.<\/p>\n\n\n\n<p>Os dejamos un video resumen de sitios donde buscar contenidos y recursos libres y un poco de informaci\u00f3n de licencias. Pero si os quedan dudas, tambi\u00e9n os ofrecemos un curso en abierto y gratuito donde podr\u00e9is formaros sobre estos de temas de contenidos libres y su b\u00fasqueda.<strong> <a href=\"http:\/\/educainternet.es\/courses\/6\">!Es este curso!<\/a><\/strong> (<a href=\"http:\/\/educainternet.es\/courses\/6\">http:\/\/educainternet.es\/courses\/6<\/a>)<\/p>\n\n\n\n<p>Y ahora el video:<\/p>\n\n\n\n<div style=\"text-align:center\"><iframe loading=\"lazy\" width=\"100%\" height=\"400\" src=\"https:\/\/www.youtube.com\/embed\/RU4m9GA3ocI\" allowfullscreen=\"\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>B\u00fasqueda de recursos libres \u00bfHab\u00e9is pensado alguna vez si se puede utilizar todo lo que encontramos online? La respuesta es sencilla. No se puede. Pero entonces, \u00bftengo que crearme todos los materiales con herramientas de autor y aprender a utilizar m\u00faltiples de ellas o comprar contenidos pagando con el bajo &#8230;<\/p>\n","protected":false},"author":1,"featured_media":6528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26,2,126],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/posts\/6524"}],"collection":[{"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/comments?post=6524"}],"version-history":[{"count":4,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/posts\/6524\/revisions"}],"predecessor-version":[{"id":6529,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/posts\/6524\/revisions\/6529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/media\/6528"}],"wp:attachment":[{"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/media?parent=6524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/categories?post=6524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/tags?post=6524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}