{"id":6297,"date":"2017-12-04T11:09:06","date_gmt":"2017-12-04T11:09:06","guid":{"rendered":"http:\/\/35.242.223.250\/?p=6297"},"modified":"2020-02-14T08:52:59","modified_gmt":"2020-02-14T08:52:59","slug":"que-sabe-google-sobre-mi","status":"publish","type":"post","link":"https:\/\/blog.educainternet.es\/index.php\/2017\/12\/04\/que-sabe-google-sobre-mi\/","title":{"rendered":"\u00bfQu\u00e9 sabe Google sobre mi?"},"content":{"rendered":"<h2>\u00bfQu\u00e9 sabe Google sobre mi?<\/h2>\n<p>En esta ocasi\u00f3n hemos preparado un video y unos enlaces para poder concienciarnos no solo de la <a href=\"http:\/\/repositorio.educainternet.es\/search?utf8=%E2%9C%93&amp;q=privacidad&amp;type=Learning_object\">privacidad<\/a> y lo importante que es su configuraci\u00f3n, sino tambi\u00e9n de cuanta informaci\u00f3n tenemos online y lo importante que es protegerla con una <a href=\"http:\/\/repositorio.educainternet.es\/search?utf8=%E2%9C%93&amp;q=contrase%C3%B1a&amp;type=Learning_object\">contrase\u00f1a segura<\/a>. \u00bfOs imagin\u00e1is que toda la informaci\u00f3n que se muestra en el video fuese accesible por un tercero? Pues eso es lo que pasar\u00e1 si tenemos una contrase\u00f1a d\u00e9bil o si la compartimos o\u00a0 la escribimos en canales no adecuados.<\/p>\n<h3>Enlaces\u00a0 para saber cu\u00e1nto sabe Google sobre nosotros:<\/h3>\n<p>Preferencias de anuncios (gustos, etc) -&gt;<a href=\"https:\/\/www.google.com\/ads\/preferences\/\">\u00a0https:\/\/www.google.com\/ads\/preferences\/<\/a><\/p>\n<p>Hist\u00f3rico de localizaci\u00f3n -&gt;\u00a0<a href=\"https:\/\/maps.google.com\/locationhistory\">https:\/\/maps.google.com\/locationhistory<\/a><\/p>\n<p>Hist\u00f3rico de b\u00fasquedas en Google -&gt;\u00a0<a href=\"https:\/\/history.google.com\">https:\/\/history.google.com<\/a><\/p>\n<p>Hist\u00f3rico de b\u00fasquedas en Youtube -&gt;\u00a0<a href=\"https:\/\/www.youtube.com\/feed\/history\/search_history\">https:\/\/www.youtube.com\/feed\/history\/search_history<\/a><\/p>\n<p>Hist\u00f3rico de videos de Youtube vistos -&gt;\u00a0<a href=\"https:\/\/www.youtube.com\/feed\/history\">https:\/\/www.youtube.com\/feed\/history<\/a><\/p>\n<p>Qu\u00e9 dispositivos pueden acceder a mis datos -&gt;\u00a0<a href=\"https:\/\/security.google.com\/settings\/security\/activity\">https:\/\/security.google.com\/settings\/security\/activity<\/a><\/p>\n<h3>Ahora el video de demostraci\u00f3n y explicaci\u00f3n<\/h3>\n<div class=\"fve-video-wrapper fve-image-embed fve-thumbnail-image youtube\" style=\"padding-bottom:75%;\">\n    <iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/MLkOpTpbJ7E?wmode=transparent&#038;modestbranding=1&#038;autohide=1&#038;showinfo=0&#038;rel=0\" width=\"100%\" height=\"100%\" frameborder=\"0\" webkitAllowFullScreen mozallowfullscreen allowFullScreen><\/iframe>    <\/div>\n<p>Si hab\u00e9is visto el video y consultado los links la primera pregunta que os surge es \u00bfC\u00f3mo o d\u00f3nde\u00a0desactivo la mayor parte de los datos que \u00abpresto\u00bb a Google? Estamos aqu\u00ed para ayudaros, usar el siguiente enlace -&gt;\u00a0<a href=\"https:\/\/myaccount.google.com\/activitycontrols\">https:\/\/myaccount.google.com\/activitycontrols<\/a><\/p>\n<p>Si quer\u00e9is seguir teniendo activos estos datos online, lo mejor que pod\u00e9is hacer es utilizar contrase\u00f1as seguras. M\u00e1s sobre ello en el siguiente videopost.<\/p>\n<p>Pero os ponemos aqu\u00ed un adelanto, pod\u00e9is comprobar la fortaleza de vuestras contrase\u00f1as o de ideas de contrase\u00f1as que teng\u00e1is aqu\u00ed -&gt;\u00a0<a href=\"https:\/\/password.kaspersky.com\/es\/\">https:\/\/password.kaspersky.com\/es\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 sabe Google sobre mi? En esta ocasi\u00f3n hemos preparado un video y unos enlaces para poder concienciarnos no solo de la privacidad y lo importante que es su configuraci\u00f3n, sino tambi\u00e9n de cuanta informaci\u00f3n tenemos online y lo importante que es protegerla con una contrase\u00f1a segura. \u00bfOs imagin\u00e1is que &#8230;<\/p>\n","protected":false},"author":1,"featured_media":6312,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,126],"tags":[127,128,5],"_links":{"self":[{"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/posts\/6297"}],"collection":[{"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/comments?post=6297"}],"version-history":[{"count":10,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/posts\/6297\/revisions"}],"predecessor-version":[{"id":6564,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/posts\/6297\/revisions\/6564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/media\/6312"}],"wp:attachment":[{"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/media?parent=6297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/categories?post=6297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.educainternet.es\/index.php\/wp-json\/wp\/v2\/tags?post=6297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}